{"id":5396,"date":"2022-08-12T10:13:17","date_gmt":"2022-08-12T08:13:17","guid":{"rendered":"https:\/\/fotofrangonz.com\/?post_type=portfolio&#038;p=5396"},"modified":"2022-08-12T14:59:34","modified_gmt":"2022-08-12T12:59:34","slug":"autorretratos","status":"publish","type":"portfolio","link":"https:\/\/fotofrangonz.com\/es\/portfolio\/autorretratos","title":{"rendered":"Autorretratos"},"content":{"rendered":"<div class=\"wp-block-visual-portfolio\">\n<div class=\"vp-portfolio vp-uid-b7871e60 vp-id-bvsns\"\n\tdata-vp-layout=\"justified\" data-vp-content-source=\"images\" data-vp-items-style=\"default\" data-vp-items-click-action=\"popup_gallery\" data-vp-items-gap=\"0\" data-vp-items-gap-vertical=\"\" data-vp-pagination=\"load-more\" data-vp-next-page-url=\"\" data-vp-justified-row-height=\"486\" data-vp-justified-row-height-tolerance=\"0.25\" data-vp-justified-max-rows-count=\"0\" data-vp-justified-last-row=\"left\" >\n\t<div class=\"vp-portfolio__preloader-wrap\">\n\t\t<div class=\"vp-portfolio__preloader\">\n\t\t\t<img decoding=\"async\" loading=\"eager\" src=\"https:\/\/fotofrangonz.com\/wp-content\/plugins\/visual-portfolio\/assets\/images\/logo-dark.svg\" alt=\"Visual Portfolio, Posts &amp; Image Gallery para WordPress\" width=\"20\" height=\"20\" data-skip-lazy>\n\t\t<\/div>\n\t<\/div>\n\t\t<div class=\"vp-portfolio__items-wrap\">\n\t\t\t\n<div class=\"vp-portfolio__items vp-portfolio__items-style-default vp-portfolio__items-show-overlay-hover\">\n\n\t\t<div\t\tclass=\"vp-portfolio__item-wrap vp-portfolio__item-uid-69a85482\" data-vp-filter=\"\" \t\t>\n\t\t\t<template class=\"vp-portfolio__item-popup\" style=\"display: none\" data-vp-popup-img=\"https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/07\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00022.jpg?fit=1280%2C1920&#038;ssl=1\" data-vp-popup-img-srcset=\"https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/07\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00022.jpg?w=1280&amp;ssl=1 1280w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/07\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00022.jpg?resize=600%2C900&amp;ssl=1 600w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/07\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00022.jpg?resize=200%2C300&amp;ssl=1 200w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/07\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00022.jpg?resize=683%2C1024&amp;ssl=1 683w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/07\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00022.jpg?resize=1024%2C1536&amp;ssl=1 1024w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/07\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00022.jpg?resize=500%2C750&amp;ssl=1 500w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/07\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00022.jpg?resize=800%2C1200&amp;ssl=1 800w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/07\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00022.jpg?resize=1240%2C1860&amp;ssl=1 1240w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/07\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00022.jpg?resize=508%2C762&amp;ssl=1 508w\" data-vp-popup-img-size=\"1280x1920\" data-vp-popup-md-img=\"https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/07\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00022.jpg?fit=800%2C1200&#038;ssl=1\" data-vp-popup-md-img-size=\"800x1200\" data-vp-popup-sm-img=\"https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/07\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00022.jpg?fit=500%2C750&#038;ssl=1\" data-vp-popup-sm-img-size=\"500x750\">\n\t\t\t<h3 class=\"vp-portfolio__item-popup-title\">francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00022<\/h3>\n\t\t<\/template>\n\t\t\t\t\t\t<figure class=\"vp-portfolio__item\">\n\t\t\t\t\n<div class=\"vp-portfolio__item-img-wrap\">\n    <div class=\"vp-portfolio__item-img\">\n        \t<a\n\t\thref=\"https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/07\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00022.jpg?fit=1280%2C1920&#038;ssl=1\"\n\t\t\t>\n\t\n        <noscript><img loading=\"lazy\" decoding=\"async\" width=\"1280\" height=\"1920\" data-skip-lazy src=\"https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/07\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00022.jpg?fit=1280%2C1920&amp;ssl=1\" class=\"wp-image-5300\" alt=\"\" srcset=\"https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/07\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00022.jpg?w=1280&amp;ssl=1 1280w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/07\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00022.jpg?resize=600%2C900&amp;ssl=1 600w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/07\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00022.jpg?resize=200%2C300&amp;ssl=1 200w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/07\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00022.jpg?resize=683%2C1024&amp;ssl=1 683w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/07\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00022.jpg?resize=1024%2C1536&amp;ssl=1 1024w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/07\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00022.jpg?resize=500%2C750&amp;ssl=1 500w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/07\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00022.jpg?resize=800%2C1200&amp;ssl=1 800w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/07\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00022.jpg?resize=1240%2C1860&amp;ssl=1 1240w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/07\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00022.jpg?resize=508%2C762&amp;ssl=1 508w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" \/><\/noscript><img fetchpriority=\"high\" decoding=\"async\" width=\"1280\" height=\"1920\" src=\"https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/07\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00022.jpg?fit=1280%2C1920&amp;ssl=1\" class=\"wp-image-5300 vp-lazyload\" alt srcset=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMTI4MCIgaGVpZ2h0PSIxOTIwIiB2aWV3Qm94PSIwIDAgMTI4MCAxOTIwIiBmaWxsPSJub25lIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" data-src=\"https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/07\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00022.jpg?fit=1280%2C1920&amp;ssl=1\" data-srcset=\"https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/07\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00022.jpg?w=1280&amp;ssl=1 1280w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/07\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00022.jpg?resize=600%2C900&amp;ssl=1 600w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/07\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00022.jpg?resize=200%2C300&amp;ssl=1 200w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/07\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00022.jpg?resize=683%2C1024&amp;ssl=1 683w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/07\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00022.jpg?resize=1024%2C1536&amp;ssl=1 1024w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/07\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00022.jpg?resize=500%2C750&amp;ssl=1 500w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/07\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00022.jpg?resize=800%2C1200&amp;ssl=1 800w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/07\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00022.jpg?resize=1240%2C1860&amp;ssl=1 1240w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/07\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00022.jpg?resize=508%2C762&amp;ssl=1 508w\" data-sizes=\"auto\" loading=\"eager\">\n        <div class=\"vp-portfolio__item-img-overlay\">\n                    <\/div>\n\n        <\/a>    <\/div>\n<\/div>\n\n<figcaption class=\"vp-portfolio__item-overlay vp-portfolio__item-align-center\">\n    <\/figcaption>\n\t\t\t<\/figure>\n\t\t\t\t\t<\/div>\n\t\t\n\t\t<div\t\tclass=\"vp-portfolio__item-wrap vp-portfolio__item-uid-4b80b132\" data-vp-filter=\"\" \t\t>\n\t\t\t<template class=\"vp-portfolio__item-popup\" style=\"display: none\" data-vp-popup-img=\"https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00017.jpg?fit=1280%2C1920&#038;ssl=1\" data-vp-popup-img-srcset=\"https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00017.jpg?w=1280&amp;ssl=1 1280w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00017.jpg?resize=600%2C900&amp;ssl=1 600w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00017.jpg?resize=200%2C300&amp;ssl=1 200w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00017.jpg?resize=683%2C1024&amp;ssl=1 683w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00017.jpg?resize=1024%2C1536&amp;ssl=1 1024w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00017.jpg?resize=500%2C750&amp;ssl=1 500w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00017.jpg?resize=800%2C1200&amp;ssl=1 800w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00017.jpg?resize=1240%2C1860&amp;ssl=1 1240w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00017.jpg?resize=508%2C762&amp;ssl=1 508w\" data-vp-popup-img-size=\"1280x1920\" data-vp-popup-md-img=\"https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00017.jpg?fit=800%2C1200&#038;ssl=1\" data-vp-popup-md-img-size=\"800x1200\" data-vp-popup-sm-img=\"https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00017.jpg?fit=500%2C750&#038;ssl=1\" data-vp-popup-sm-img-size=\"500x750\">\n\t\t\t<h3 class=\"vp-portfolio__item-popup-title\">francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00017<\/h3>\n\t\t<\/template>\n\t\t\t\t\t\t<figure class=\"vp-portfolio__item\">\n\t\t\t\t\n<div class=\"vp-portfolio__item-img-wrap\">\n    <div class=\"vp-portfolio__item-img\">\n        \t<a\n\t\thref=\"https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00017.jpg?fit=1280%2C1920&#038;ssl=1\"\n\t\t\t>\n\t\n        <noscript><img loading=\"lazy\" decoding=\"async\" width=\"1280\" height=\"1920\" data-skip-lazy src=\"https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00017.jpg?fit=1280%2C1920&amp;ssl=1\" class=\"wp-image-5419\" alt=\"\" srcset=\"https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00017.jpg?w=1280&amp;ssl=1 1280w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00017.jpg?resize=600%2C900&amp;ssl=1 600w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00017.jpg?resize=200%2C300&amp;ssl=1 200w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00017.jpg?resize=683%2C1024&amp;ssl=1 683w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00017.jpg?resize=1024%2C1536&amp;ssl=1 1024w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00017.jpg?resize=500%2C750&amp;ssl=1 500w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00017.jpg?resize=800%2C1200&amp;ssl=1 800w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00017.jpg?resize=1240%2C1860&amp;ssl=1 1240w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00017.jpg?resize=508%2C762&amp;ssl=1 508w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" \/><\/noscript><img decoding=\"async\" width=\"1280\" height=\"1920\" src=\"https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00017.jpg?fit=1280%2C1920&amp;ssl=1\" class=\"wp-image-5419 vp-lazyload\" alt srcset=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMTI4MCIgaGVpZ2h0PSIxOTIwIiB2aWV3Qm94PSIwIDAgMTI4MCAxOTIwIiBmaWxsPSJub25lIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" data-src=\"https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00017.jpg?fit=1280%2C1920&amp;ssl=1\" data-srcset=\"https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00017.jpg?w=1280&amp;ssl=1 1280w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00017.jpg?resize=600%2C900&amp;ssl=1 600w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00017.jpg?resize=200%2C300&amp;ssl=1 200w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00017.jpg?resize=683%2C1024&amp;ssl=1 683w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00017.jpg?resize=1024%2C1536&amp;ssl=1 1024w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00017.jpg?resize=500%2C750&amp;ssl=1 500w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00017.jpg?resize=800%2C1200&amp;ssl=1 800w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00017.jpg?resize=1240%2C1860&amp;ssl=1 1240w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00017.jpg?resize=508%2C762&amp;ssl=1 508w\" data-sizes=\"auto\" loading=\"eager\">\n        <div class=\"vp-portfolio__item-img-overlay\">\n                    <\/div>\n\n        <\/a>    <\/div>\n<\/div>\n\n<figcaption class=\"vp-portfolio__item-overlay vp-portfolio__item-align-center\">\n    <\/figcaption>\n\t\t\t<\/figure>\n\t\t\t\t\t<\/div>\n\t\t\n\t\t<div\t\tclass=\"vp-portfolio__item-wrap vp-portfolio__item-uid-9158b585\" data-vp-filter=\"\" \t\t>\n\t\t\t<template class=\"vp-portfolio__item-popup\" style=\"display: none\" data-vp-popup-img=\"https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00016.jpg?fit=1280%2C1920&#038;ssl=1\" data-vp-popup-img-srcset=\"https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00016.jpg?w=1280&amp;ssl=1 1280w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00016.jpg?resize=600%2C900&amp;ssl=1 600w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00016.jpg?resize=200%2C300&amp;ssl=1 200w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00016.jpg?resize=683%2C1024&amp;ssl=1 683w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00016.jpg?resize=1024%2C1536&amp;ssl=1 1024w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00016.jpg?resize=500%2C750&amp;ssl=1 500w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00016.jpg?resize=800%2C1200&amp;ssl=1 800w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00016.jpg?resize=1240%2C1860&amp;ssl=1 1240w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00016.jpg?resize=508%2C762&amp;ssl=1 508w\" data-vp-popup-img-size=\"1280x1920\" data-vp-popup-md-img=\"https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00016.jpg?fit=800%2C1200&#038;ssl=1\" data-vp-popup-md-img-size=\"800x1200\" data-vp-popup-sm-img=\"https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00016.jpg?fit=500%2C750&#038;ssl=1\" data-vp-popup-sm-img-size=\"500x750\">\n\t\t\t<h3 class=\"vp-portfolio__item-popup-title\">francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00016<\/h3>\n\t\t<\/template>\n\t\t\t\t\t\t<figure class=\"vp-portfolio__item\">\n\t\t\t\t\n<div class=\"vp-portfolio__item-img-wrap\">\n    <div class=\"vp-portfolio__item-img\">\n        \t<a\n\t\thref=\"https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00016.jpg?fit=1280%2C1920&#038;ssl=1\"\n\t\t\t>\n\t\n        <noscript><img loading=\"lazy\" decoding=\"async\" width=\"1280\" height=\"1920\" data-skip-lazy src=\"https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00016.jpg?fit=1280%2C1920&amp;ssl=1\" class=\"wp-image-5417\" alt=\"\" srcset=\"https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00016.jpg?w=1280&amp;ssl=1 1280w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00016.jpg?resize=600%2C900&amp;ssl=1 600w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00016.jpg?resize=200%2C300&amp;ssl=1 200w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00016.jpg?resize=683%2C1024&amp;ssl=1 683w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00016.jpg?resize=1024%2C1536&amp;ssl=1 1024w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00016.jpg?resize=500%2C750&amp;ssl=1 500w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00016.jpg?resize=800%2C1200&amp;ssl=1 800w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00016.jpg?resize=1240%2C1860&amp;ssl=1 1240w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00016.jpg?resize=508%2C762&amp;ssl=1 508w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" \/><\/noscript><img decoding=\"async\" width=\"1280\" height=\"1920\" src=\"https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00016.jpg?fit=1280%2C1920&amp;ssl=1\" class=\"wp-image-5417 vp-lazyload\" alt srcset=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMTI4MCIgaGVpZ2h0PSIxOTIwIiB2aWV3Qm94PSIwIDAgMTI4MCAxOTIwIiBmaWxsPSJub25lIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" data-src=\"https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00016.jpg?fit=1280%2C1920&amp;ssl=1\" data-srcset=\"https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00016.jpg?w=1280&amp;ssl=1 1280w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00016.jpg?resize=600%2C900&amp;ssl=1 600w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00016.jpg?resize=200%2C300&amp;ssl=1 200w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00016.jpg?resize=683%2C1024&amp;ssl=1 683w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00016.jpg?resize=1024%2C1536&amp;ssl=1 1024w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00016.jpg?resize=500%2C750&amp;ssl=1 500w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00016.jpg?resize=800%2C1200&amp;ssl=1 800w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00016.jpg?resize=1240%2C1860&amp;ssl=1 1240w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00016.jpg?resize=508%2C762&amp;ssl=1 508w\" data-sizes=\"auto\" loading=\"eager\">\n        <div class=\"vp-portfolio__item-img-overlay\">\n                    <\/div>\n\n        <\/a>    <\/div>\n<\/div>\n\n<figcaption class=\"vp-portfolio__item-overlay vp-portfolio__item-align-center\">\n    <\/figcaption>\n\t\t\t<\/figure>\n\t\t\t\t\t<\/div>\n\t\t\n\t\t<div\t\tclass=\"vp-portfolio__item-wrap vp-portfolio__item-uid-4fc583c7\" data-vp-filter=\"\" \t\t>\n\t\t\t<template class=\"vp-portfolio__item-popup\" style=\"display: none\" data-vp-popup-img=\"https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00015.jpg?fit=1280%2C1920&#038;ssl=1\" data-vp-popup-img-srcset=\"https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00015.jpg?w=1280&amp;ssl=1 1280w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00015.jpg?resize=600%2C900&amp;ssl=1 600w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00015.jpg?resize=200%2C300&amp;ssl=1 200w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00015.jpg?resize=683%2C1024&amp;ssl=1 683w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00015.jpg?resize=1024%2C1536&amp;ssl=1 1024w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00015.jpg?resize=500%2C750&amp;ssl=1 500w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00015.jpg?resize=800%2C1200&amp;ssl=1 800w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00015.jpg?resize=1240%2C1860&amp;ssl=1 1240w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00015.jpg?resize=508%2C762&amp;ssl=1 508w\" data-vp-popup-img-size=\"1280x1920\" data-vp-popup-md-img=\"https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00015.jpg?fit=800%2C1200&#038;ssl=1\" data-vp-popup-md-img-size=\"800x1200\" data-vp-popup-sm-img=\"https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00015.jpg?fit=500%2C750&#038;ssl=1\" data-vp-popup-sm-img-size=\"500x750\">\n\t\t\t<h3 class=\"vp-portfolio__item-popup-title\">francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00015<\/h3>\n\t\t<\/template>\n\t\t\t\t\t\t<figure class=\"vp-portfolio__item\">\n\t\t\t\t\n<div class=\"vp-portfolio__item-img-wrap\">\n    <div class=\"vp-portfolio__item-img\">\n        \t<a\n\t\thref=\"https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00015.jpg?fit=1280%2C1920&#038;ssl=1\"\n\t\t\t>\n\t\n        <noscript><img loading=\"lazy\" decoding=\"async\" width=\"1280\" height=\"1920\" data-skip-lazy src=\"https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00015.jpg?fit=1280%2C1920&amp;ssl=1\" class=\"wp-image-5415\" alt=\"\" srcset=\"https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00015.jpg?w=1280&amp;ssl=1 1280w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00015.jpg?resize=600%2C900&amp;ssl=1 600w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00015.jpg?resize=200%2C300&amp;ssl=1 200w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00015.jpg?resize=683%2C1024&amp;ssl=1 683w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00015.jpg?resize=1024%2C1536&amp;ssl=1 1024w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00015.jpg?resize=500%2C750&amp;ssl=1 500w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00015.jpg?resize=800%2C1200&amp;ssl=1 800w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00015.jpg?resize=1240%2C1860&amp;ssl=1 1240w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00015.jpg?resize=508%2C762&amp;ssl=1 508w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" \/><\/noscript><img decoding=\"async\" width=\"1280\" height=\"1920\" src=\"https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00015.jpg?fit=1280%2C1920&amp;ssl=1\" class=\"wp-image-5415 vp-lazyload\" alt srcset=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMTI4MCIgaGVpZ2h0PSIxOTIwIiB2aWV3Qm94PSIwIDAgMTI4MCAxOTIwIiBmaWxsPSJub25lIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" data-src=\"https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00015.jpg?fit=1280%2C1920&amp;ssl=1\" data-srcset=\"https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00015.jpg?w=1280&amp;ssl=1 1280w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00015.jpg?resize=600%2C900&amp;ssl=1 600w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00015.jpg?resize=200%2C300&amp;ssl=1 200w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00015.jpg?resize=683%2C1024&amp;ssl=1 683w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00015.jpg?resize=1024%2C1536&amp;ssl=1 1024w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00015.jpg?resize=500%2C750&amp;ssl=1 500w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00015.jpg?resize=800%2C1200&amp;ssl=1 800w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00015.jpg?resize=1240%2C1860&amp;ssl=1 1240w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00015.jpg?resize=508%2C762&amp;ssl=1 508w\" data-sizes=\"auto\" loading=\"eager\">\n        <div class=\"vp-portfolio__item-img-overlay\">\n                    <\/div>\n\n        <\/a>    <\/div>\n<\/div>\n\n<figcaption class=\"vp-portfolio__item-overlay vp-portfolio__item-align-center\">\n    <\/figcaption>\n\t\t\t<\/figure>\n\t\t\t\t\t<\/div>\n\t\t\n\t\t<div\t\tclass=\"vp-portfolio__item-wrap vp-portfolio__item-uid-9bc60f42\" data-vp-filter=\"\" \t\t>\n\t\t\t<template class=\"vp-portfolio__item-popup\" style=\"display: none\" data-vp-popup-img=\"https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00014.jpg?fit=1920%2C1920&#038;ssl=1\" data-vp-popup-img-srcset=\"https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00014.jpg?w=1920&amp;ssl=1 1920w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00014.jpg?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00014.jpg?resize=100%2C100&amp;ssl=1 100w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00014.jpg?resize=600%2C600&amp;ssl=1 600w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00014.jpg?resize=1024%2C1024&amp;ssl=1 1024w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00014.jpg?resize=30%2C30&amp;ssl=1 30w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00014.jpg?resize=1536%2C1536&amp;ssl=1 1536w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00014.jpg?resize=500%2C500&amp;ssl=1 500w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00014.jpg?resize=800%2C800&amp;ssl=1 800w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00014.jpg?resize=1280%2C1280&amp;ssl=1 1280w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00014.jpg?resize=1240%2C1240&amp;ssl=1 1240w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00014.jpg?resize=508%2C508&amp;ssl=1 508w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00014.jpg?w=1800&amp;ssl=1 1800w\" data-vp-popup-img-size=\"1920x1920\" data-vp-popup-md-img=\"https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00014.jpg?fit=800%2C800&#038;ssl=1\" data-vp-popup-md-img-size=\"800x800\" data-vp-popup-sm-img=\"https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00014.jpg?fit=500%2C500&#038;ssl=1\" data-vp-popup-sm-img-size=\"500x500\">\n\t\t\t<h3 class=\"vp-portfolio__item-popup-title\">francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00014<\/h3>\n\t\t<\/template>\n\t\t\t\t\t\t<figure class=\"vp-portfolio__item\">\n\t\t\t\t\n<div class=\"vp-portfolio__item-img-wrap\">\n    <div class=\"vp-portfolio__item-img\">\n        \t<a\n\t\thref=\"https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00014.jpg?fit=1920%2C1920&#038;ssl=1\"\n\t\t\t>\n\t\n        <noscript><img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"1920\" data-skip-lazy src=\"https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00014.jpg?fit=1920%2C1920&amp;ssl=1\" class=\"wp-image-5413\" alt=\"\" srcset=\"https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00014.jpg?w=1920&amp;ssl=1 1920w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00014.jpg?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00014.jpg?resize=100%2C100&amp;ssl=1 100w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00014.jpg?resize=600%2C600&amp;ssl=1 600w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00014.jpg?resize=1024%2C1024&amp;ssl=1 1024w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00014.jpg?resize=30%2C30&amp;ssl=1 30w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00014.jpg?resize=1536%2C1536&amp;ssl=1 1536w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00014.jpg?resize=500%2C500&amp;ssl=1 500w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00014.jpg?resize=800%2C800&amp;ssl=1 800w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00014.jpg?resize=1280%2C1280&amp;ssl=1 1280w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00014.jpg?resize=1240%2C1240&amp;ssl=1 1240w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00014.jpg?resize=508%2C508&amp;ssl=1 508w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00014.jpg?w=1800&amp;ssl=1 1800w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" \/><\/noscript><img decoding=\"async\" width=\"1920\" height=\"1920\" src=\"https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00014.jpg?fit=1920%2C1920&amp;ssl=1\" class=\"wp-image-5413 vp-lazyload\" alt srcset=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMTkyMCIgaGVpZ2h0PSIxOTIwIiB2aWV3Qm94PSIwIDAgMTkyMCAxOTIwIiBmaWxsPSJub25lIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" data-src=\"https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00014.jpg?fit=1920%2C1920&amp;ssl=1\" data-srcset=\"https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00014.jpg?w=1920&amp;ssl=1 1920w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00014.jpg?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00014.jpg?resize=100%2C100&amp;ssl=1 100w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00014.jpg?resize=600%2C600&amp;ssl=1 600w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00014.jpg?resize=1024%2C1024&amp;ssl=1 1024w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00014.jpg?resize=30%2C30&amp;ssl=1 30w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00014.jpg?resize=1536%2C1536&amp;ssl=1 1536w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00014.jpg?resize=500%2C500&amp;ssl=1 500w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00014.jpg?resize=800%2C800&amp;ssl=1 800w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00014.jpg?resize=1280%2C1280&amp;ssl=1 1280w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00014.jpg?resize=1240%2C1240&amp;ssl=1 1240w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00014.jpg?resize=508%2C508&amp;ssl=1 508w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00014.jpg?w=1800&amp;ssl=1 1800w\" data-sizes=\"auto\" loading=\"eager\">\n        <div class=\"vp-portfolio__item-img-overlay\">\n                    <\/div>\n\n        <\/a>    <\/div>\n<\/div>\n\n<figcaption class=\"vp-portfolio__item-overlay vp-portfolio__item-align-center\">\n    <\/figcaption>\n\t\t\t<\/figure>\n\t\t\t\t\t<\/div>\n\t\t\n\t\t<div\t\tclass=\"vp-portfolio__item-wrap vp-portfolio__item-uid-f798f9bf\" data-vp-filter=\"\" \t\t>\n\t\t\t<template class=\"vp-portfolio__item-popup\" style=\"display: none\" data-vp-popup-img=\"https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00013.jpg?fit=1280%2C1920&#038;ssl=1\" data-vp-popup-img-srcset=\"https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00013.jpg?w=1280&amp;ssl=1 1280w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00013.jpg?resize=600%2C900&amp;ssl=1 600w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00013.jpg?resize=200%2C300&amp;ssl=1 200w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00013.jpg?resize=683%2C1024&amp;ssl=1 683w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00013.jpg?resize=1024%2C1536&amp;ssl=1 1024w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00013.jpg?resize=500%2C750&amp;ssl=1 500w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00013.jpg?resize=800%2C1200&amp;ssl=1 800w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00013.jpg?resize=1240%2C1860&amp;ssl=1 1240w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00013.jpg?resize=508%2C762&amp;ssl=1 508w\" data-vp-popup-img-size=\"1280x1920\" data-vp-popup-md-img=\"https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00013.jpg?fit=800%2C1200&#038;ssl=1\" data-vp-popup-md-img-size=\"800x1200\" data-vp-popup-sm-img=\"https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00013.jpg?fit=500%2C750&#038;ssl=1\" data-vp-popup-sm-img-size=\"500x750\">\n\t\t\t<h3 class=\"vp-portfolio__item-popup-title\">francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00013<\/h3>\n\t\t<\/template>\n\t\t\t\t\t\t<figure class=\"vp-portfolio__item\">\n\t\t\t\t\n<div class=\"vp-portfolio__item-img-wrap\">\n    <div class=\"vp-portfolio__item-img\">\n        \t<a\n\t\thref=\"https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00013.jpg?fit=1280%2C1920&#038;ssl=1\"\n\t\t\t>\n\t\n        <noscript><img loading=\"lazy\" decoding=\"async\" width=\"1280\" height=\"1920\" data-skip-lazy src=\"https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00013.jpg?fit=1280%2C1920&amp;ssl=1\" class=\"wp-image-5411\" alt=\"\" srcset=\"https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00013.jpg?w=1280&amp;ssl=1 1280w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00013.jpg?resize=600%2C900&amp;ssl=1 600w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00013.jpg?resize=200%2C300&amp;ssl=1 200w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00013.jpg?resize=683%2C1024&amp;ssl=1 683w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00013.jpg?resize=1024%2C1536&amp;ssl=1 1024w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00013.jpg?resize=500%2C750&amp;ssl=1 500w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00013.jpg?resize=800%2C1200&amp;ssl=1 800w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00013.jpg?resize=1240%2C1860&amp;ssl=1 1240w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00013.jpg?resize=508%2C762&amp;ssl=1 508w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" \/><\/noscript><img decoding=\"async\" width=\"1280\" height=\"1920\" src=\"https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00013.jpg?fit=1280%2C1920&amp;ssl=1\" class=\"wp-image-5411 vp-lazyload\" alt srcset=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMTI4MCIgaGVpZ2h0PSIxOTIwIiB2aWV3Qm94PSIwIDAgMTI4MCAxOTIwIiBmaWxsPSJub25lIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" data-src=\"https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00013.jpg?fit=1280%2C1920&amp;ssl=1\" data-srcset=\"https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00013.jpg?w=1280&amp;ssl=1 1280w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00013.jpg?resize=600%2C900&amp;ssl=1 600w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00013.jpg?resize=200%2C300&amp;ssl=1 200w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00013.jpg?resize=683%2C1024&amp;ssl=1 683w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00013.jpg?resize=1024%2C1536&amp;ssl=1 1024w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00013.jpg?resize=500%2C750&amp;ssl=1 500w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00013.jpg?resize=800%2C1200&amp;ssl=1 800w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00013.jpg?resize=1240%2C1860&amp;ssl=1 1240w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00013.jpg?resize=508%2C762&amp;ssl=1 508w\" data-sizes=\"auto\" loading=\"eager\">\n        <div class=\"vp-portfolio__item-img-overlay\">\n                    <\/div>\n\n        <\/a>    <\/div>\n<\/div>\n\n<figcaption class=\"vp-portfolio__item-overlay vp-portfolio__item-align-center\">\n    <\/figcaption>\n\t\t\t<\/figure>\n\t\t\t\t\t<\/div>\n\t\t\n\t\t<div\t\tclass=\"vp-portfolio__item-wrap vp-portfolio__item-uid-dd38697c\" data-vp-filter=\"\" \t\t>\n\t\t\t<template class=\"vp-portfolio__item-popup\" style=\"display: none\" data-vp-popup-img=\"https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00012.jpg?fit=1280%2C1920&#038;ssl=1\" data-vp-popup-img-srcset=\"https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00012.jpg?w=1280&amp;ssl=1 1280w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00012.jpg?resize=600%2C900&amp;ssl=1 600w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00012.jpg?resize=200%2C300&amp;ssl=1 200w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00012.jpg?resize=683%2C1024&amp;ssl=1 683w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00012.jpg?resize=1024%2C1536&amp;ssl=1 1024w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00012.jpg?resize=500%2C750&amp;ssl=1 500w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00012.jpg?resize=800%2C1200&amp;ssl=1 800w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00012.jpg?resize=1240%2C1860&amp;ssl=1 1240w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00012.jpg?resize=508%2C762&amp;ssl=1 508w\" data-vp-popup-img-size=\"1280x1920\" data-vp-popup-md-img=\"https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00012.jpg?fit=800%2C1200&#038;ssl=1\" data-vp-popup-md-img-size=\"800x1200\" data-vp-popup-sm-img=\"https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00012.jpg?fit=500%2C750&#038;ssl=1\" data-vp-popup-sm-img-size=\"500x750\">\n\t\t\t<h3 class=\"vp-portfolio__item-popup-title\">francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00012<\/h3>\n\t\t<\/template>\n\t\t\t\t\t\t<figure class=\"vp-portfolio__item\">\n\t\t\t\t\n<div class=\"vp-portfolio__item-img-wrap\">\n    <div class=\"vp-portfolio__item-img\">\n        \t<a\n\t\thref=\"https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00012.jpg?fit=1280%2C1920&#038;ssl=1\"\n\t\t\t>\n\t\n        <noscript><img loading=\"lazy\" decoding=\"async\" width=\"1280\" height=\"1920\" data-skip-lazy src=\"https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00012.jpg?fit=1280%2C1920&amp;ssl=1\" class=\"wp-image-5409\" alt=\"\" srcset=\"https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00012.jpg?w=1280&amp;ssl=1 1280w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00012.jpg?resize=600%2C900&amp;ssl=1 600w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00012.jpg?resize=200%2C300&amp;ssl=1 200w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00012.jpg?resize=683%2C1024&amp;ssl=1 683w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00012.jpg?resize=1024%2C1536&amp;ssl=1 1024w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00012.jpg?resize=500%2C750&amp;ssl=1 500w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00012.jpg?resize=800%2C1200&amp;ssl=1 800w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00012.jpg?resize=1240%2C1860&amp;ssl=1 1240w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00012.jpg?resize=508%2C762&amp;ssl=1 508w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" \/><\/noscript><img decoding=\"async\" width=\"1280\" height=\"1920\" src=\"https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00012.jpg?fit=1280%2C1920&amp;ssl=1\" class=\"wp-image-5409 vp-lazyload\" alt srcset=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMTI4MCIgaGVpZ2h0PSIxOTIwIiB2aWV3Qm94PSIwIDAgMTI4MCAxOTIwIiBmaWxsPSJub25lIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" data-src=\"https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00012.jpg?fit=1280%2C1920&amp;ssl=1\" data-srcset=\"https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00012.jpg?w=1280&amp;ssl=1 1280w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00012.jpg?resize=600%2C900&amp;ssl=1 600w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00012.jpg?resize=200%2C300&amp;ssl=1 200w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00012.jpg?resize=683%2C1024&amp;ssl=1 683w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00012.jpg?resize=1024%2C1536&amp;ssl=1 1024w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00012.jpg?resize=500%2C750&amp;ssl=1 500w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00012.jpg?resize=800%2C1200&amp;ssl=1 800w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00012.jpg?resize=1240%2C1860&amp;ssl=1 1240w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00012.jpg?resize=508%2C762&amp;ssl=1 508w\" data-sizes=\"auto\" loading=\"eager\">\n        <div class=\"vp-portfolio__item-img-overlay\">\n                    <\/div>\n\n        <\/a>    <\/div>\n<\/div>\n\n<figcaption class=\"vp-portfolio__item-overlay vp-portfolio__item-align-center\">\n    <\/figcaption>\n\t\t\t<\/figure>\n\t\t\t\t\t<\/div>\n\t\t\n\t\t<div\t\tclass=\"vp-portfolio__item-wrap vp-portfolio__item-uid-7d203eab\" data-vp-filter=\"\" \t\t>\n\t\t\t<template class=\"vp-portfolio__item-popup\" style=\"display: none\" data-vp-popup-img=\"https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00011.jpg?fit=1280%2C1920&#038;ssl=1\" data-vp-popup-img-srcset=\"https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00011.jpg?w=1280&amp;ssl=1 1280w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00011.jpg?resize=600%2C900&amp;ssl=1 600w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00011.jpg?resize=200%2C300&amp;ssl=1 200w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00011.jpg?resize=683%2C1024&amp;ssl=1 683w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00011.jpg?resize=1024%2C1536&amp;ssl=1 1024w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00011.jpg?resize=500%2C750&amp;ssl=1 500w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00011.jpg?resize=800%2C1200&amp;ssl=1 800w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00011.jpg?resize=1240%2C1860&amp;ssl=1 1240w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00011.jpg?resize=508%2C762&amp;ssl=1 508w\" data-vp-popup-img-size=\"1280x1920\" data-vp-popup-md-img=\"https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00011.jpg?fit=800%2C1200&#038;ssl=1\" data-vp-popup-md-img-size=\"800x1200\" data-vp-popup-sm-img=\"https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00011.jpg?fit=500%2C750&#038;ssl=1\" data-vp-popup-sm-img-size=\"500x750\">\n\t\t\t<h3 class=\"vp-portfolio__item-popup-title\">francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00011<\/h3>\n\t\t<\/template>\n\t\t\t\t\t\t<figure class=\"vp-portfolio__item\">\n\t\t\t\t\n<div class=\"vp-portfolio__item-img-wrap\">\n    <div class=\"vp-portfolio__item-img\">\n        \t<a\n\t\thref=\"https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00011.jpg?fit=1280%2C1920&#038;ssl=1\"\n\t\t\t>\n\t\n        <noscript><img loading=\"lazy\" decoding=\"async\" width=\"1280\" height=\"1920\" data-skip-lazy src=\"https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00011.jpg?fit=1280%2C1920&amp;ssl=1\" class=\"wp-image-5407\" alt=\"\" srcset=\"https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00011.jpg?w=1280&amp;ssl=1 1280w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00011.jpg?resize=600%2C900&amp;ssl=1 600w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00011.jpg?resize=200%2C300&amp;ssl=1 200w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00011.jpg?resize=683%2C1024&amp;ssl=1 683w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00011.jpg?resize=1024%2C1536&amp;ssl=1 1024w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00011.jpg?resize=500%2C750&amp;ssl=1 500w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00011.jpg?resize=800%2C1200&amp;ssl=1 800w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00011.jpg?resize=1240%2C1860&amp;ssl=1 1240w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00011.jpg?resize=508%2C762&amp;ssl=1 508w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" \/><\/noscript><img decoding=\"async\" width=\"1280\" height=\"1920\" src=\"https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00011.jpg?fit=1280%2C1920&amp;ssl=1\" class=\"wp-image-5407 vp-lazyload\" alt srcset=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMTI4MCIgaGVpZ2h0PSIxOTIwIiB2aWV3Qm94PSIwIDAgMTI4MCAxOTIwIiBmaWxsPSJub25lIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" data-src=\"https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00011.jpg?fit=1280%2C1920&amp;ssl=1\" data-srcset=\"https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00011.jpg?w=1280&amp;ssl=1 1280w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00011.jpg?resize=600%2C900&amp;ssl=1 600w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00011.jpg?resize=200%2C300&amp;ssl=1 200w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00011.jpg?resize=683%2C1024&amp;ssl=1 683w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00011.jpg?resize=1024%2C1536&amp;ssl=1 1024w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00011.jpg?resize=500%2C750&amp;ssl=1 500w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00011.jpg?resize=800%2C1200&amp;ssl=1 800w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00011.jpg?resize=1240%2C1860&amp;ssl=1 1240w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00011.jpg?resize=508%2C762&amp;ssl=1 508w\" data-sizes=\"auto\" loading=\"eager\">\n        <div class=\"vp-portfolio__item-img-overlay\">\n                    <\/div>\n\n        <\/a>    <\/div>\n<\/div>\n\n<figcaption class=\"vp-portfolio__item-overlay vp-portfolio__item-align-center\">\n    <\/figcaption>\n\t\t\t<\/figure>\n\t\t\t\t\t<\/div>\n\t\t\n\t\t<div\t\tclass=\"vp-portfolio__item-wrap vp-portfolio__item-uid-ae4e7637\" data-vp-filter=\"\" \t\t>\n\t\t\t<template class=\"vp-portfolio__item-popup\" style=\"display: none\" data-vp-popup-img=\"https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00010.jpg?fit=1920%2C1920&#038;ssl=1\" data-vp-popup-img-srcset=\"https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00010.jpg?w=1920&amp;ssl=1 1920w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00010.jpg?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00010.jpg?resize=100%2C100&amp;ssl=1 100w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00010.jpg?resize=600%2C600&amp;ssl=1 600w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00010.jpg?resize=1024%2C1024&amp;ssl=1 1024w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00010.jpg?resize=30%2C30&amp;ssl=1 30w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00010.jpg?resize=1536%2C1536&amp;ssl=1 1536w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00010.jpg?resize=500%2C500&amp;ssl=1 500w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00010.jpg?resize=800%2C800&amp;ssl=1 800w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00010.jpg?resize=1280%2C1280&amp;ssl=1 1280w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00010.jpg?resize=1240%2C1240&amp;ssl=1 1240w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00010.jpg?resize=508%2C508&amp;ssl=1 508w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00010.jpg?w=1800&amp;ssl=1 1800w\" data-vp-popup-img-size=\"1920x1920\" data-vp-popup-md-img=\"https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00010.jpg?fit=800%2C800&#038;ssl=1\" data-vp-popup-md-img-size=\"800x800\" data-vp-popup-sm-img=\"https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00010.jpg?fit=500%2C500&#038;ssl=1\" data-vp-popup-sm-img-size=\"500x500\">\n\t\t\t<h3 class=\"vp-portfolio__item-popup-title\">francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00010<\/h3>\n\t\t<\/template>\n\t\t\t\t\t\t<figure class=\"vp-portfolio__item\">\n\t\t\t\t\n<div class=\"vp-portfolio__item-img-wrap\">\n    <div class=\"vp-portfolio__item-img\">\n        \t<a\n\t\thref=\"https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00010.jpg?fit=1920%2C1920&#038;ssl=1\"\n\t\t\t>\n\t\n        <noscript><img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"1920\" data-skip-lazy src=\"https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00010.jpg?fit=1920%2C1920&amp;ssl=1\" class=\"wp-image-5405\" alt=\"\" srcset=\"https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00010.jpg?w=1920&amp;ssl=1 1920w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00010.jpg?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00010.jpg?resize=100%2C100&amp;ssl=1 100w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00010.jpg?resize=600%2C600&amp;ssl=1 600w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00010.jpg?resize=1024%2C1024&amp;ssl=1 1024w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00010.jpg?resize=30%2C30&amp;ssl=1 30w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00010.jpg?resize=1536%2C1536&amp;ssl=1 1536w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00010.jpg?resize=500%2C500&amp;ssl=1 500w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00010.jpg?resize=800%2C800&amp;ssl=1 800w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00010.jpg?resize=1280%2C1280&amp;ssl=1 1280w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00010.jpg?resize=1240%2C1240&amp;ssl=1 1240w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00010.jpg?resize=508%2C508&amp;ssl=1 508w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00010.jpg?w=1800&amp;ssl=1 1800w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" \/><\/noscript><img decoding=\"async\" width=\"1920\" height=\"1920\" src=\"https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00010.jpg?fit=1920%2C1920&amp;ssl=1\" class=\"wp-image-5405 vp-lazyload\" alt srcset=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMTkyMCIgaGVpZ2h0PSIxOTIwIiB2aWV3Qm94PSIwIDAgMTkyMCAxOTIwIiBmaWxsPSJub25lIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" data-src=\"https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00010.jpg?fit=1920%2C1920&amp;ssl=1\" data-srcset=\"https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00010.jpg?w=1920&amp;ssl=1 1920w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00010.jpg?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00010.jpg?resize=100%2C100&amp;ssl=1 100w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00010.jpg?resize=600%2C600&amp;ssl=1 600w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00010.jpg?resize=1024%2C1024&amp;ssl=1 1024w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00010.jpg?resize=30%2C30&amp;ssl=1 30w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00010.jpg?resize=1536%2C1536&amp;ssl=1 1536w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00010.jpg?resize=500%2C500&amp;ssl=1 500w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00010.jpg?resize=800%2C800&amp;ssl=1 800w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00010.jpg?resize=1280%2C1280&amp;ssl=1 1280w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00010.jpg?resize=1240%2C1240&amp;ssl=1 1240w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00010.jpg?resize=508%2C508&amp;ssl=1 508w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00010.jpg?w=1800&amp;ssl=1 1800w\" data-sizes=\"auto\" loading=\"eager\">\n        <div class=\"vp-portfolio__item-img-overlay\">\n                    <\/div>\n\n        <\/a>    <\/div>\n<\/div>\n\n<figcaption class=\"vp-portfolio__item-overlay vp-portfolio__item-align-center\">\n    <\/figcaption>\n\t\t\t<\/figure>\n\t\t\t\t\t<\/div>\n\t\t\n\t\t<div\t\tclass=\"vp-portfolio__item-wrap vp-portfolio__item-uid-f50d0f12\" data-vp-filter=\"\" \t\t>\n\t\t\t<template class=\"vp-portfolio__item-popup\" style=\"display: none\" data-vp-popup-img=\"https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00009.jpg?fit=1920%2C1280&#038;ssl=1\" data-vp-popup-img-srcset=\"https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00009.jpg?w=1920&amp;ssl=1 1920w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00009.jpg?resize=600%2C400&amp;ssl=1 600w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00009.jpg?resize=300%2C200&amp;ssl=1 300w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00009.jpg?resize=1024%2C683&amp;ssl=1 1024w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00009.jpg?resize=1536%2C1024&amp;ssl=1 1536w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00009.jpg?resize=500%2C333&amp;ssl=1 500w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00009.jpg?resize=800%2C533&amp;ssl=1 800w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00009.jpg?resize=1280%2C853&amp;ssl=1 1280w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00009.jpg?resize=1240%2C827&amp;ssl=1 1240w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00009.jpg?resize=508%2C339&amp;ssl=1 508w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00009.jpg?w=1800&amp;ssl=1 1800w\" data-vp-popup-img-size=\"1920x1280\" data-vp-popup-md-img=\"https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00009.jpg?fit=800%2C533&#038;ssl=1\" data-vp-popup-md-img-size=\"800x533\" data-vp-popup-sm-img=\"https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00009.jpg?fit=500%2C333&#038;ssl=1\" data-vp-popup-sm-img-size=\"500x333\">\n\t\t\t<h3 class=\"vp-portfolio__item-popup-title\">francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00009<\/h3>\n\t\t<\/template>\n\t\t\t\t\t\t<figure class=\"vp-portfolio__item\">\n\t\t\t\t\n<div class=\"vp-portfolio__item-img-wrap\">\n    <div class=\"vp-portfolio__item-img\">\n        \t<a\n\t\thref=\"https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00009.jpg?fit=1920%2C1280&#038;ssl=1\"\n\t\t\t>\n\t\n        <noscript><img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"1280\" data-skip-lazy src=\"https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00009.jpg?fit=1920%2C1280&amp;ssl=1\" class=\"wp-image-5403\" alt=\"\" srcset=\"https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00009.jpg?w=1920&amp;ssl=1 1920w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00009.jpg?resize=600%2C400&amp;ssl=1 600w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00009.jpg?resize=300%2C200&amp;ssl=1 300w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00009.jpg?resize=1024%2C683&amp;ssl=1 1024w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00009.jpg?resize=1536%2C1024&amp;ssl=1 1536w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00009.jpg?resize=500%2C333&amp;ssl=1 500w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00009.jpg?resize=800%2C533&amp;ssl=1 800w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00009.jpg?resize=1280%2C853&amp;ssl=1 1280w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00009.jpg?resize=1240%2C827&amp;ssl=1 1240w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00009.jpg?resize=508%2C339&amp;ssl=1 508w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00009.jpg?w=1800&amp;ssl=1 1800w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" \/><\/noscript><img decoding=\"async\" width=\"1920\" height=\"1280\" src=\"https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00009.jpg?fit=1920%2C1280&amp;ssl=1\" class=\"wp-image-5403 vp-lazyload\" alt srcset=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMTkyMCIgaGVpZ2h0PSIxMjgwIiB2aWV3Qm94PSIwIDAgMTkyMCAxMjgwIiBmaWxsPSJub25lIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" data-src=\"https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00009.jpg?fit=1920%2C1280&amp;ssl=1\" data-srcset=\"https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00009.jpg?w=1920&amp;ssl=1 1920w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00009.jpg?resize=600%2C400&amp;ssl=1 600w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00009.jpg?resize=300%2C200&amp;ssl=1 300w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00009.jpg?resize=1024%2C683&amp;ssl=1 1024w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00009.jpg?resize=1536%2C1024&amp;ssl=1 1536w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00009.jpg?resize=500%2C333&amp;ssl=1 500w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00009.jpg?resize=800%2C533&amp;ssl=1 800w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00009.jpg?resize=1280%2C853&amp;ssl=1 1280w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00009.jpg?resize=1240%2C827&amp;ssl=1 1240w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00009.jpg?resize=508%2C339&amp;ssl=1 508w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00009.jpg?w=1800&amp;ssl=1 1800w\" data-sizes=\"auto\" loading=\"eager\">\n        <div class=\"vp-portfolio__item-img-overlay\">\n                    <\/div>\n\n        <\/a>    <\/div>\n<\/div>\n\n<figcaption class=\"vp-portfolio__item-overlay vp-portfolio__item-align-center\">\n    <\/figcaption>\n\t\t\t<\/figure>\n\t\t\t\t\t<\/div>\n\t\t\n\t\t<div\t\tclass=\"vp-portfolio__item-wrap vp-portfolio__item-uid-2663478e\" data-vp-filter=\"\" \t\t>\n\t\t\t<template class=\"vp-portfolio__item-popup\" style=\"display: none\" data-vp-popup-img=\"https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00008.jpg?fit=1280%2C1920&#038;ssl=1\" data-vp-popup-img-srcset=\"https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00008.jpg?w=1280&amp;ssl=1 1280w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00008.jpg?resize=600%2C900&amp;ssl=1 600w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00008.jpg?resize=200%2C300&amp;ssl=1 200w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00008.jpg?resize=683%2C1024&amp;ssl=1 683w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00008.jpg?resize=1024%2C1536&amp;ssl=1 1024w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00008.jpg?resize=500%2C750&amp;ssl=1 500w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00008.jpg?resize=800%2C1200&amp;ssl=1 800w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00008.jpg?resize=1240%2C1860&amp;ssl=1 1240w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00008.jpg?resize=508%2C762&amp;ssl=1 508w\" data-vp-popup-img-size=\"1280x1920\" data-vp-popup-md-img=\"https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00008.jpg?fit=800%2C1200&#038;ssl=1\" data-vp-popup-md-img-size=\"800x1200\" data-vp-popup-sm-img=\"https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00008.jpg?fit=500%2C750&#038;ssl=1\" data-vp-popup-sm-img-size=\"500x750\">\n\t\t\t<h3 class=\"vp-portfolio__item-popup-title\">francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00008<\/h3>\n\t\t<\/template>\n\t\t\t\t\t\t<figure class=\"vp-portfolio__item\">\n\t\t\t\t\n<div class=\"vp-portfolio__item-img-wrap\">\n    <div class=\"vp-portfolio__item-img\">\n        \t<a\n\t\thref=\"https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00008.jpg?fit=1280%2C1920&#038;ssl=1\"\n\t\t\t>\n\t\n        <noscript><img loading=\"lazy\" decoding=\"async\" width=\"1280\" height=\"1920\" data-skip-lazy src=\"https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00008.jpg?fit=1280%2C1920&amp;ssl=1\" class=\"wp-image-5401\" alt=\"\" srcset=\"https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00008.jpg?w=1280&amp;ssl=1 1280w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00008.jpg?resize=600%2C900&amp;ssl=1 600w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00008.jpg?resize=200%2C300&amp;ssl=1 200w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00008.jpg?resize=683%2C1024&amp;ssl=1 683w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00008.jpg?resize=1024%2C1536&amp;ssl=1 1024w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00008.jpg?resize=500%2C750&amp;ssl=1 500w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00008.jpg?resize=800%2C1200&amp;ssl=1 800w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00008.jpg?resize=1240%2C1860&amp;ssl=1 1240w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00008.jpg?resize=508%2C762&amp;ssl=1 508w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" \/><\/noscript><img decoding=\"async\" width=\"1280\" height=\"1920\" src=\"https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00008.jpg?fit=1280%2C1920&amp;ssl=1\" class=\"wp-image-5401 vp-lazyload\" alt srcset=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMTI4MCIgaGVpZ2h0PSIxOTIwIiB2aWV3Qm94PSIwIDAgMTI4MCAxOTIwIiBmaWxsPSJub25lIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" data-src=\"https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00008.jpg?fit=1280%2C1920&amp;ssl=1\" data-srcset=\"https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00008.jpg?w=1280&amp;ssl=1 1280w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00008.jpg?resize=600%2C900&amp;ssl=1 600w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00008.jpg?resize=200%2C300&amp;ssl=1 200w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00008.jpg?resize=683%2C1024&amp;ssl=1 683w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00008.jpg?resize=1024%2C1536&amp;ssl=1 1024w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00008.jpg?resize=500%2C750&amp;ssl=1 500w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00008.jpg?resize=800%2C1200&amp;ssl=1 800w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00008.jpg?resize=1240%2C1860&amp;ssl=1 1240w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00008.jpg?resize=508%2C762&amp;ssl=1 508w\" data-sizes=\"auto\" loading=\"eager\">\n        <div class=\"vp-portfolio__item-img-overlay\">\n                    <\/div>\n\n        <\/a>    <\/div>\n<\/div>\n\n<figcaption class=\"vp-portfolio__item-overlay vp-portfolio__item-align-center\">\n    <\/figcaption>\n\t\t\t<\/figure>\n\t\t\t\t\t<\/div>\n\t\t\n\t\t<div\t\tclass=\"vp-portfolio__item-wrap vp-portfolio__item-uid-bb9518a0\" data-vp-filter=\"\" \t\t>\n\t\t\t<template class=\"vp-portfolio__item-popup\" style=\"display: none\" data-vp-popup-img=\"https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00007.jpg?fit=1280%2C1920&#038;ssl=1\" data-vp-popup-img-srcset=\"https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00007.jpg?w=1280&amp;ssl=1 1280w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00007.jpg?resize=600%2C900&amp;ssl=1 600w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00007.jpg?resize=200%2C300&amp;ssl=1 200w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00007.jpg?resize=683%2C1024&amp;ssl=1 683w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00007.jpg?resize=1024%2C1536&amp;ssl=1 1024w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00007.jpg?resize=500%2C750&amp;ssl=1 500w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00007.jpg?resize=800%2C1200&amp;ssl=1 800w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00007.jpg?resize=1240%2C1860&amp;ssl=1 1240w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00007.jpg?resize=508%2C762&amp;ssl=1 508w\" data-vp-popup-img-size=\"1280x1920\" data-vp-popup-md-img=\"https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00007.jpg?fit=800%2C1200&#038;ssl=1\" data-vp-popup-md-img-size=\"800x1200\" data-vp-popup-sm-img=\"https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00007.jpg?fit=500%2C750&#038;ssl=1\" data-vp-popup-sm-img-size=\"500x750\">\n\t\t\t<h3 class=\"vp-portfolio__item-popup-title\">francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00007<\/h3>\n\t\t<\/template>\n\t\t\t\t\t\t<figure class=\"vp-portfolio__item\">\n\t\t\t\t\n<div class=\"vp-portfolio__item-img-wrap\">\n    <div class=\"vp-portfolio__item-img\">\n        \t<a\n\t\thref=\"https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00007.jpg?fit=1280%2C1920&#038;ssl=1\"\n\t\t\t>\n\t\n        <noscript><img loading=\"lazy\" decoding=\"async\" width=\"1280\" height=\"1920\" data-skip-lazy src=\"https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00007.jpg?fit=1280%2C1920&amp;ssl=1\" class=\"wp-image-5399\" alt=\"\" srcset=\"https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00007.jpg?w=1280&amp;ssl=1 1280w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00007.jpg?resize=600%2C900&amp;ssl=1 600w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00007.jpg?resize=200%2C300&amp;ssl=1 200w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00007.jpg?resize=683%2C1024&amp;ssl=1 683w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00007.jpg?resize=1024%2C1536&amp;ssl=1 1024w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00007.jpg?resize=500%2C750&amp;ssl=1 500w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00007.jpg?resize=800%2C1200&amp;ssl=1 800w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00007.jpg?resize=1240%2C1860&amp;ssl=1 1240w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00007.jpg?resize=508%2C762&amp;ssl=1 508w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" \/><\/noscript><img decoding=\"async\" width=\"1280\" height=\"1920\" src=\"https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00007.jpg?fit=1280%2C1920&amp;ssl=1\" class=\"wp-image-5399 vp-lazyload\" alt srcset=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMTI4MCIgaGVpZ2h0PSIxOTIwIiB2aWV3Qm94PSIwIDAgMTI4MCAxOTIwIiBmaWxsPSJub25lIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" data-src=\"https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00007.jpg?fit=1280%2C1920&amp;ssl=1\" data-srcset=\"https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00007.jpg?w=1280&amp;ssl=1 1280w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00007.jpg?resize=600%2C900&amp;ssl=1 600w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00007.jpg?resize=200%2C300&amp;ssl=1 200w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00007.jpg?resize=683%2C1024&amp;ssl=1 683w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00007.jpg?resize=1024%2C1536&amp;ssl=1 1024w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00007.jpg?resize=500%2C750&amp;ssl=1 500w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00007.jpg?resize=800%2C1200&amp;ssl=1 800w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00007.jpg?resize=1240%2C1860&amp;ssl=1 1240w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00007.jpg?resize=508%2C762&amp;ssl=1 508w\" data-sizes=\"auto\" loading=\"eager\">\n        <div class=\"vp-portfolio__item-img-overlay\">\n                    <\/div>\n\n        <\/a>    <\/div>\n<\/div>\n\n<figcaption class=\"vp-portfolio__item-overlay vp-portfolio__item-align-center\">\n    <\/figcaption>\n\t\t\t<\/figure>\n\t\t\t\t\t<\/div>\n\t\t\n\t\t<div\t\tclass=\"vp-portfolio__item-wrap vp-portfolio__item-uid-614d1c17\" data-vp-filter=\"\" \t\t>\n\t\t\t<template class=\"vp-portfolio__item-popup\" style=\"display: none\" data-vp-popup-img=\"https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00006.jpg?fit=1200%2C1920&#038;ssl=1\" data-vp-popup-img-srcset=\"https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00006.jpg?w=1200&amp;ssl=1 1200w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00006.jpg?resize=600%2C960&amp;ssl=1 600w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00006.jpg?resize=188%2C300&amp;ssl=1 188w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00006.jpg?resize=640%2C1024&amp;ssl=1 640w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00006.jpg?resize=960%2C1536&amp;ssl=1 960w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00006.jpg?resize=500%2C800&amp;ssl=1 500w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00006.jpg?resize=800%2C1280&amp;ssl=1 800w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00006.jpg?resize=508%2C813&amp;ssl=1 508w\" data-vp-popup-img-size=\"1200x1920\" data-vp-popup-md-img=\"https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00006.jpg?fit=800%2C1280&#038;ssl=1\" data-vp-popup-md-img-size=\"800x1280\" data-vp-popup-sm-img=\"https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00006.jpg?fit=500%2C800&#038;ssl=1\" data-vp-popup-sm-img-size=\"500x800\">\n\t\t\t<h3 class=\"vp-portfolio__item-popup-title\">francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00006<\/h3>\n\t\t<\/template>\n\t\t\t\t\t\t<figure class=\"vp-portfolio__item\">\n\t\t\t\t\n<div class=\"vp-portfolio__item-img-wrap\">\n    <div class=\"vp-portfolio__item-img\">\n        \t<a\n\t\thref=\"https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00006.jpg?fit=1200%2C1920&#038;ssl=1\"\n\t\t\t>\n\t\n        <noscript><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"1920\" data-skip-lazy src=\"https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00006.jpg?fit=1200%2C1920&amp;ssl=1\" class=\"wp-image-5397\" alt=\"\" srcset=\"https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00006.jpg?w=1200&amp;ssl=1 1200w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00006.jpg?resize=600%2C960&amp;ssl=1 600w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00006.jpg?resize=188%2C300&amp;ssl=1 188w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00006.jpg?resize=640%2C1024&amp;ssl=1 640w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00006.jpg?resize=960%2C1536&amp;ssl=1 960w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00006.jpg?resize=500%2C800&amp;ssl=1 500w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00006.jpg?resize=800%2C1280&amp;ssl=1 800w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00006.jpg?resize=508%2C813&amp;ssl=1 508w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" \/><\/noscript><img decoding=\"async\" width=\"1200\" height=\"1920\" src=\"https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00006.jpg?fit=1200%2C1920&amp;ssl=1\" class=\"wp-image-5397 vp-lazyload\" alt srcset=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMTIwMCIgaGVpZ2h0PSIxOTIwIiB2aWV3Qm94PSIwIDAgMTIwMCAxOTIwIiBmaWxsPSJub25lIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" data-src=\"https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00006.jpg?fit=1200%2C1920&amp;ssl=1\" data-srcset=\"https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00006.jpg?w=1200&amp;ssl=1 1200w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00006.jpg?resize=600%2C960&amp;ssl=1 600w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00006.jpg?resize=188%2C300&amp;ssl=1 188w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00006.jpg?resize=640%2C1024&amp;ssl=1 640w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00006.jpg?resize=960%2C1536&amp;ssl=1 960w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00006.jpg?resize=500%2C800&amp;ssl=1 500w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00006.jpg?resize=800%2C1280&amp;ssl=1 800w, https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00006.jpg?resize=508%2C813&amp;ssl=1 508w\" data-sizes=\"auto\" loading=\"eager\">\n        <div class=\"vp-portfolio__item-img-overlay\">\n                    <\/div>\n\n        <\/a>    <\/div>\n<\/div>\n\n<figcaption class=\"vp-portfolio__item-overlay vp-portfolio__item-align-center\">\n    <\/figcaption>\n\t\t\t<\/figure>\n\t\t\t\t\t<\/div>\n\t\t\n<\/div>\n\t\t<\/div>\n\t\t\n<\/div>\n<\/div>","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":5417,"menu_order":0,"comment_status":"open","ping_status":"closed","template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_vp_format_video_url":"","_vp_image_focal_point":[],"footnotes":""},"portfolio_category":[139],"portfolio_tag":[],"class_list":["post-5396","portfolio","type-portfolio","status-publish","format-standard","has-post-thumbnail","hentry","portfolio_category-retratos-portfolio-category"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Autorretratos - Francisco Gonz\u00e1lez SOLEMNITY<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/fotofrangonz.com\/es\/portfolio\/autorretratos\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Autorretratos - Francisco Gonz\u00e1lez SOLEMNITY\" \/>\n<meta property=\"og:url\" content=\"https:\/\/fotofrangonz.com\/es\/portfolio\/autorretratos\" \/>\n<meta property=\"og:site_name\" content=\"Francisco Gonz\u00e1lez SOLEMNITY\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/fotofrangonz\" \/>\n<meta property=\"article:modified_time\" content=\"2022-08-12T12:59:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00016.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"1920\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@fotofrangonz\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/fotofrangonz.com\\\/es\\\/portfolio\\\/autorretratos\",\"url\":\"https:\\\/\\\/fotofrangonz.com\\\/es\\\/portfolio\\\/autorretratos\",\"name\":\"Autorretratos - Francisco Gonz\u00e1lez SOLEMNITY\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fotofrangonz.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/fotofrangonz.com\\\/es\\\/portfolio\\\/autorretratos#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/fotofrangonz.com\\\/es\\\/portfolio\\\/autorretratos#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/fotofrangonz.com\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00016.jpg?fit=1280%2C1920&ssl=1\",\"datePublished\":\"2022-08-12T08:13:17+00:00\",\"dateModified\":\"2022-08-12T12:59:34+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/fotofrangonz.com\\\/es\\\/portfolio\\\/autorretratos#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/fotofrangonz.com\\\/es\\\/portfolio\\\/autorretratos\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/fotofrangonz.com\\\/es\\\/portfolio\\\/autorretratos#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/fotofrangonz.com\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00016.jpg?fit=1280%2C1920&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/fotofrangonz.com\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00016.jpg?fit=1280%2C1920&ssl=1\",\"width\":1280,\"height\":1920},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/fotofrangonz.com\\\/es\\\/portfolio\\\/autorretratos#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/fotofrangonz.com\\\/es\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Porfolio\",\"item\":\"https:\\\/\\\/fotofrangonz.com\\\/es\\\/portfolio\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Autorretratos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/fotofrangonz.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/fotofrangonz.com\\\/es\\\/\",\"name\":\"Francisco Gonz\u00e1lez SOLEMNITY\",\"description\":\"Siente la magia de la fantas\u00eda, lo \u00e9pico y majestuoso, asombro m\u00edstico y espiritual.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/fotofrangonz.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Autorretratos - Francisco Gonz\u00e1lez SOLEMNITY","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/fotofrangonz.com\/es\/portfolio\/autorretratos","og_locale":"es_ES","og_type":"article","og_title":"Autorretratos - Francisco Gonz\u00e1lez SOLEMNITY","og_url":"https:\/\/fotofrangonz.com\/es\/portfolio\/autorretratos","og_site_name":"Francisco Gonz\u00e1lez SOLEMNITY","article_publisher":"https:\/\/www.facebook.com\/fotofrangonz","article_modified_time":"2022-08-12T12:59:34+00:00","og_image":[{"width":1280,"height":1920,"url":"https:\/\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00016.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@fotofrangonz","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/fotofrangonz.com\/es\/portfolio\/autorretratos","url":"https:\/\/fotofrangonz.com\/es\/portfolio\/autorretratos","name":"Autorretratos - Francisco Gonz\u00e1lez SOLEMNITY","isPartOf":{"@id":"https:\/\/fotofrangonz.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/fotofrangonz.com\/es\/portfolio\/autorretratos#primaryimage"},"image":{"@id":"https:\/\/fotofrangonz.com\/es\/portfolio\/autorretratos#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00016.jpg?fit=1280%2C1920&ssl=1","datePublished":"2022-08-12T08:13:17+00:00","dateModified":"2022-08-12T12:59:34+00:00","breadcrumb":{"@id":"https:\/\/fotofrangonz.com\/es\/portfolio\/autorretratos#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/fotofrangonz.com\/es\/portfolio\/autorretratos"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/fotofrangonz.com\/es\/portfolio\/autorretratos#primaryimage","url":"https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00016.jpg?fit=1280%2C1920&ssl=1","contentUrl":"https:\/\/i0.wp.com\/fotofrangonz.com\/wp-content\/uploads\/2022\/08\/francisco-gonzalez-solemnity-selfportraits-cinematograselfies-00016.jpg?fit=1280%2C1920&ssl=1","width":1280,"height":1920},{"@type":"BreadcrumbList","@id":"https:\/\/fotofrangonz.com\/es\/portfolio\/autorretratos#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/fotofrangonz.com\/es"},{"@type":"ListItem","position":2,"name":"Porfolio","item":"https:\/\/fotofrangonz.com\/es\/portfolio"},{"@type":"ListItem","position":3,"name":"Autorretratos"}]},{"@type":"WebSite","@id":"https:\/\/fotofrangonz.com\/es\/#website","url":"https:\/\/fotofrangonz.com\/es\/","name":"Francisco Gonz\u00e1lez SOLEMNITY","description":"Siente la magia de la fantas\u00eda, lo \u00e9pico y majestuoso, asombro m\u00edstico y espiritual.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/fotofrangonz.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/fotofrangonz.com\/es\/wp-json\/wp\/v2\/portfolio\/5396","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fotofrangonz.com\/es\/wp-json\/wp\/v2\/portfolio"}],"about":[{"href":"https:\/\/fotofrangonz.com\/es\/wp-json\/wp\/v2\/types\/portfolio"}],"author":[{"embeddable":true,"href":"https:\/\/fotofrangonz.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/fotofrangonz.com\/es\/wp-json\/wp\/v2\/comments?post=5396"}],"version-history":[{"count":3,"href":"https:\/\/fotofrangonz.com\/es\/wp-json\/wp\/v2\/portfolio\/5396\/revisions"}],"predecessor-version":[{"id":5424,"href":"https:\/\/fotofrangonz.com\/es\/wp-json\/wp\/v2\/portfolio\/5396\/revisions\/5424"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fotofrangonz.com\/es\/wp-json\/wp\/v2\/media\/5417"}],"wp:attachment":[{"href":"https:\/\/fotofrangonz.com\/es\/wp-json\/wp\/v2\/media?parent=5396"}],"wp:term":[{"taxonomy":"portfolio_category","embeddable":true,"href":"https:\/\/fotofrangonz.com\/es\/wp-json\/wp\/v2\/portfolio_category?post=5396"},{"taxonomy":"portfolio_tag","embeddable":true,"href":"https:\/\/fotofrangonz.com\/es\/wp-json\/wp\/v2\/portfolio_tag?post=5396"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}